{"id":11828,"date":"2020-05-29T08:00:32","date_gmt":"2020-05-29T06:00:32","guid":{"rendered":"https:\/\/firagran.com\/?p=11828"},"modified":"2020-05-19T11:55:20","modified_gmt":"2020-05-19T09:55:20","slug":"abuelas-informaticas-contra-la-brecha-digital","status":"publish","type":"post","link":"https:\/\/firagran.com\/es\/abuelas-informaticas-contra-la-brecha-digital\/","title":{"rendered":"Abuelas Inform\u00e1ticas contra la brecha digital"},"content":{"rendered":"<p>Mar\u00eda Jos\u00e9 Conde, de 71 a\u00f1os, ha puesto en funcionamiento una red para transmitir conocimientos sobre las nuevas tecnolog\u00edas entre las personas mayores<\/p>\n<p>\u201cPara ayudar a mis grupos de amigas de riesgo&#8230; de m\u00e1s de 70 a\u00f1os&#8230; a pasar mejor el confinamiento, cada ma\u00f1ana les env\u00edo un whatsapp con una receta diferente y una pieza de m\u00fasica distinta: muchas prueban las recetas, todas escuchan la m\u00fasica y todas mandan comentarios\u201d.<\/p>\n<p>As\u00ed es c\u00f3mo Mar\u00eda Jos\u00e9 Conde empez\u00f3 un proyecto \u201cdistra\u00eddo y simp\u00e1tico\u201d que ha acabado convirti\u00e9ndose en una herramienta \u00fatil para poner un granito de arena para reducir la brecha digital que sufren las personas mayores.<\/p>\n<p>\u201cPor la tarde, casi cada d\u00eda les env\u00edo un peque\u00f1o v\u00eddeo donde doy ideas para mejorar sus habilidades con el m\u00f3vil\u201d, detalla Mar\u00eda Jos\u00e9 en El Reto de los Lectores de La Vanguardia.<\/p>\n<p>\u201cLos v\u00eddeos han tenido tanto \u00e9xito que la semana pasada tuve que abrir un canal de Youtube: Abuelas Inform\u00e1ticas, que est\u00e1 teniendo una gran aceptaci\u00f3n\u201d, destaca.<\/p>\n<p>Fuente: www.lavanguardia.com<\/p>\n<p>M\u00e1s informaci\u00f3n: <a href=\"https:\/\/www.lavanguardia.com\/participacion\/retos\/20200512\/481098271082\/red-abuelas-informaticas-lucha-brecha-digital-nuevas-tecnologias.html\">https:\/\/www.lavanguardia.com\/participacion\/retos\/20200512\/481098271082\/red-abuelas-informaticas-lucha-brecha-digital-nuevas-tecnologias.html<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mar\u00eda Jos\u00e9 Conde, de 71 a\u00f1os, ha puesto en funcionamiento una red para transmitir conocimientos sobre las nuevas tecnolog\u00edas entre las personas mayores \u201cPara ayudar a mis grupos de amigas de riesgo&#8230; de m\u00e1s de <a href=\"https:\/\/firagran.com\/es\/abuelas-informaticas-contra-la-brecha-digital\/\"> [&#8230;]<\/a><\/p>\n","protected":false},"author":2,"featured_media":11826,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[75,81],"tags":[],"class_list":["post-11828","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-envejecimiento-activo","category-habitos-saludables"],"_links":{"self":[{"href":"https:\/\/firagran.com\/es\/wp-json\/wp\/v2\/posts\/11828","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/firagran.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/firagran.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/firagran.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/firagran.com\/es\/wp-json\/wp\/v2\/comments?post=11828"}],"version-history":[{"count":1,"href":"https:\/\/firagran.com\/es\/wp-json\/wp\/v2\/posts\/11828\/revisions"}],"predecessor-version":[{"id":11829,"href":"https:\/\/firagran.com\/es\/wp-json\/wp\/v2\/posts\/11828\/revisions\/11829"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/firagran.com\/es\/wp-json\/wp\/v2\/media\/11826"}],"wp:attachment":[{"href":"https:\/\/firagran.com\/es\/wp-json\/wp\/v2\/media?parent=11828"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/firagran.com\/es\/wp-json\/wp\/v2\/categories?post=11828"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/firagran.com\/es\/wp-json\/wp\/v2\/tags?post=11828"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}