{"id":17243,"date":"2025-04-04T10:00:47","date_gmt":"2025-04-04T08:00:47","guid":{"rendered":"https:\/\/firagran.com\/?p=17243"},"modified":"2025-04-03T20:39:38","modified_gmt":"2025-04-03T18:39:38","slug":"reconectados-la-tecnologia-no-tiene-edad","status":"publish","type":"post","link":"https:\/\/firagran.com\/es\/reconectados-la-tecnologia-no-tiene-edad\/","title":{"rendered":"RECONECTADOS. La tecnolog\u00eda no tiene edad"},"content":{"rendered":"<p>Seg\u00fan datos del INE y Eurostat, el 73% de las personas de entre 65 y 74 a\u00f1os en Espa\u00f1a carecen de competencias digitales b\u00e1sicas, lo que sit\u00faa a este colectivo en riesgo de exclusi\u00f3n digital.<\/p>\n<p>Fundaci\u00f3n Telef\u00f3nica, conscientes de esta necesidad, cuenta con <a href=\"https:\/\/www.fundaciontelefonica.com\/voluntarios\/reconectados\/\"><em>RECONECTADOS. La tecnolog\u00eda no tiene edad<\/em><\/a><em>, un <\/em>programa de formaci\u00f3n gratuito para impulsar las competencias digitales de las personas mayores.\u00a0 El proyecto est\u00e1 compuesto por <strong>talleres presenciales, cursos de formaci\u00f3n online y recursos formativos para su entorno directo,<\/strong> ya sean familiares o profesionales.<\/p>\n<p><strong>Los talleres presenciales se imparten semanalmente en el <\/strong>Espacio Fundaci\u00f3n Telef\u00f3nica de Madrid con contenidos que giran en torno al funcionamiento del tel\u00e9fono m\u00f3vil: Whatsapp, IA, ciberseguridad, movilidad y Google Maps, banca digital, redes sociales, salud digital o carpeta ciudadana, entre otros. Adem\u00e1s, las sesiones cuentan con el apoyo y acompa\u00f1amiento de Voluntarios Telef\u00f3nica.<\/p>\n<p>Estos contenidos tambi\u00e9n est\u00e1n disponibles a trav\u00e9s de <strong>cursos online<\/strong> para que cada persona pueda hacerlos a su ritmo y en cualquier lugar, y se complementan con <strong>recursos formativos<\/strong> para familiares o profesionales que acompa\u00f1an al mayor en su d\u00eda a d\u00eda que puedan apoyarles en su proceso de aprendizaje y darles seguridad.<\/p>\n<p>Y para llegar a m\u00e1s personas, el proyecto cuenta con <strong>alianzas clave<\/strong> con entidades e instituciones como Asociaci\u00f3n Espa\u00f1ola de Banca (AEB), SECOT, SUPERCUIDADORES, Fundaci\u00f3n Legalitas, Acerca Cultura, Fundaci\u00f3n CERES, o 65YM\u00c1S, entre otros.<\/p>\n<p><strong>RECONECTADOS ON TOUR<\/strong><\/p>\n<p>Adem\u00e1s de la oferta continuada de <a href=\"https:\/\/www.fundaciontelefonica.com\/voluntarios\/reconectados\/\">RECONECTADOS<\/a>, desde Fundaci\u00f3n Telef\u00f3nica promueven el debate p\u00fablico sobre el tema de la adopci\u00f3n digital, aumentando su visibilidad en diferentes puntos de Espa\u00f1a con encuentros y congresos de la mano de los principales actores.<\/p>\n<p>Es el caso de la FiraGran de L\u2019Hospitalet donde los participantes podr\u00e1n asistir a 3 talleres que Fundaci\u00f3n Telef\u00f3nica impartir\u00e1 durante la feria sobre ciberseguridad, Whatsapp o Tu d\u00eda a d\u00eda m\u00e1s f\u00e1cil con el m\u00f3vil.\u00a0 Las formaciones les permitir\u00e1n conocer la importancia de proteger el dispositivo, navegar por internet de forma segura o identificar ataques y amenazas, entre otros.<\/p>\n<p><strong>&#x1f449; www.fundaciontelefonica.com\/voluntarios\/reconectados\/<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Seg\u00fan datos del INE y Eurostat, el 73% de las personas de entre 65 y 74 a\u00f1os en Espa\u00f1a carecen de competencias digitales b\u00e1sicas, lo que sit\u00faa a este colectivo en riesgo de exclusi\u00f3n digital. <a href=\"https:\/\/firagran.com\/es\/reconectados-la-tecnologia-no-tiene-edad\/\"> [&#8230;]<\/a><\/p>\n","protected":false},"author":1,"featured_media":17241,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[106,78,79],"tags":[],"class_list":["post-17243","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-firagran-es","category-formacion","category-nuevas-tecnologias"],"_links":{"self":[{"href":"https:\/\/firagran.com\/es\/wp-json\/wp\/v2\/posts\/17243","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/firagran.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/firagran.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/firagran.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/firagran.com\/es\/wp-json\/wp\/v2\/comments?post=17243"}],"version-history":[{"count":2,"href":"https:\/\/firagran.com\/es\/wp-json\/wp\/v2\/posts\/17243\/revisions"}],"predecessor-version":[{"id":17245,"href":"https:\/\/firagran.com\/es\/wp-json\/wp\/v2\/posts\/17243\/revisions\/17245"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/firagran.com\/es\/wp-json\/wp\/v2\/media\/17241"}],"wp:attachment":[{"href":"https:\/\/firagran.com\/es\/wp-json\/wp\/v2\/media?parent=17243"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/firagran.com\/es\/wp-json\/wp\/v2\/categories?post=17243"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/firagran.com\/es\/wp-json\/wp\/v2\/tags?post=17243"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}