{"id":4746,"date":"2018-03-02T08:59:36","date_gmt":"2018-03-02T07:59:36","guid":{"rendered":"https:\/\/firagran.com\/?p=4746"},"modified":"2018-02-26T17:01:58","modified_gmt":"2018-02-26T16:01:58","slug":"los-abuelos-toman-menos-farmacos-en-las-residencias","status":"publish","type":"post","link":"https:\/\/firagran.com\/es\/los-abuelos-toman-menos-farmacos-en-las-residencias\/","title":{"rendered":"Los abuelos toman menos f\u00e1rmacos en las residencias"},"content":{"rendered":"<div id=\"gt-res-content\">\n<div id=\"gt-res-dir-ctr\" class=\"trans-verified-button-small\" dir=\"ltr\"><span id=\"result_box\" lang=\"es\">Un 20% de los ancianos consumen m\u00e1s de tres f\u00e1rmacos. De esta sobreabundancia, a veces no del todo controlada ni siquiera necesaria, se dice polimedicaci\u00f3n. Varios expertos han alertado de su riesgo para la calidad de vida de las personas mayores y el propio Departamento de Salud busca sistemas de racionalizaci\u00f3n que no siempre resultan f\u00e1ciles, en especial cuando los abuelos viven solos. La Asociaci\u00f3n Catalana de Recursos Asistenciales (ACRA), que agrupa el 70% de las entidades que ofrecen recursos de atenci\u00f3n a la gente mayor, present\u00f3 ayer un estudio, realizado a un millar de usuarios de 21 residencias, que quiere contribuir a mejorar esta problem\u00e1tica.<\/span><\/div>\n<div class=\"trans-verified-button-small\" dir=\"ltr\"><span id=\"result_box\" lang=\"es\"><br \/>\nEl doctor Toni Andreu, director de estrategia de ACRA y coordinador del estudio, explic\u00f3 que &#8220;la reducci\u00f3n m\u00e1s importante se da en aquellos f\u00e1rmacos relacionados con patolog\u00edas en que los h\u00e1bitos de vida saludables tienen un papel fundamental&#8221;.<\/span><\/div>\n<\/div>\n<div id=\"gt-res-tools\">\n<div id=\"gt-res-tools-l\">\n<div id=\"gt-pb-star\">\n<div class=\"goog-toolbar-button goog-inline-block trans-pb-button\" tabindex=\"0\" role=\"button\" aria-hidden=\"false\" aria-label=\"Desat\" data-tooltip-align=\"t,c\" data-tooltip=\"Desat\"><\/div>\n<\/div>\n<div id=\"gt-res-copy\" class=\"copy-button goog-toolbar-button\" tabindex=\"0\" role=\"button\" aria-hidden=\"false\" aria-label=\"Copia\" data-tooltip-align=\"t,c\" data-tooltip=\"Copia\"><\/div>\n<div id=\"gt-res-listen\" class=\"trans-listen-button goog-toolbar-button\" tabindex=\"0\" role=\"button\" aria-disabled=\"false\" aria-hidden=\"false\" aria-pressed=\"false\" aria-label=\"Escolta\" data-tooltip-align=\"t,c\" data-tooltip=\"Escolta\"><\/div>\n<div id=\"gt-res-share\" class=\"share-button goog-toolbar-button\" tabindex=\"0\" role=\"button\" aria-hidden=\"false\" aria-label=\"Comparteix\" data-tooltip-align=\"t,c\" data-tooltip=\"Comparteix\">Fuente:http:\/\/www.elpuntavui.cat\/societat\/article\/5-societat\/1346163-els-avis-prenen-menys-farmacs-a-les-residencies.html<\/div>\n<div tabindex=\"0\" role=\"button\" aria-hidden=\"false\" aria-label=\"Comparteix\" data-tooltip-align=\"t,c\" data-tooltip=\"Comparteix\">Leer m\u00e1s:\u00a0http:\/\/www.elpuntavui.cat<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Un 20% de los ancianos consumen m\u00e1s de tres f\u00e1rmacos. De esta sobreabundancia, a veces no del todo controlada ni siquiera necesaria, se dice polimedicaci\u00f3n. Varios expertos han alertado de su riesgo para la calidad <a href=\"https:\/\/firagran.com\/es\/los-abuelos-toman-menos-farmacos-en-las-residencias\/\"> [&#8230;]<\/a><\/p>\n","protected":false},"author":1,"featured_media":4744,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[28],"tags":[],"class_list":["post-4746","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-general-es"],"_links":{"self":[{"href":"https:\/\/firagran.com\/es\/wp-json\/wp\/v2\/posts\/4746","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/firagran.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/firagran.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/firagran.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/firagran.com\/es\/wp-json\/wp\/v2\/comments?post=4746"}],"version-history":[{"count":1,"href":"https:\/\/firagran.com\/es\/wp-json\/wp\/v2\/posts\/4746\/revisions"}],"predecessor-version":[{"id":4747,"href":"https:\/\/firagran.com\/es\/wp-json\/wp\/v2\/posts\/4746\/revisions\/4747"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/firagran.com\/es\/wp-json\/wp\/v2\/media\/4744"}],"wp:attachment":[{"href":"https:\/\/firagran.com\/es\/wp-json\/wp\/v2\/media?parent=4746"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/firagran.com\/es\/wp-json\/wp\/v2\/categories?post=4746"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/firagran.com\/es\/wp-json\/wp\/v2\/tags?post=4746"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}