{"id":4825,"date":"2018-03-22T08:53:36","date_gmt":"2018-03-22T07:53:36","guid":{"rendered":"https:\/\/firagran.com\/?p=4825"},"modified":"2018-03-20T09:56:49","modified_gmt":"2018-03-20T08:56:49","slug":"cambrils-renueva-el-convenio-para-luchar-contra-la-soledad-de-las-personas-mayores","status":"publish","type":"post","link":"https:\/\/firagran.com\/es\/cambrils-renueva-el-convenio-para-luchar-contra-la-soledad-de-las-personas-mayores\/","title":{"rendered":"Cambrils renueva el convenio para luchar contra la soledad de las personas mayores"},"content":{"rendered":"<p><span id=\"result_box\" lang=\"es\">El <strong>Ayuntamiento de Cambrils<\/strong> y la <strong>Fundaci\u00f3n Privada Amigos de los Mayores<\/strong> han firmado un nuevo convenio para continuar trabajando a favor de las personas mayores en situaci\u00f3n de soledad. La actividad que desarrolla Amigos de los Mayores complementa los servicios que se prestan desde el Ayuntamiento a las personas mayores de 65 a\u00f1os, que viven solas y que sufren situaciones precarias. La entidad especializada en el acompa\u00f1amiento a trav\u00e9s de personal voluntario trabajar\u00e1 coordinadamente con la concejal\u00eda de Bienestar Social de <span tabindex=\"-1\" contenteditable=\"false\">del Ayuntamiento<\/span> de Cambrils, en el tratamiento de los casos detectados por los Servicios B\u00e1sicos.<\/span><\/p>\n<p><span id=\"result_box\" lang=\"es\"><br \/>\nPor su parte, el <strong>Ayuntamiento<\/strong> pondr\u00e1 a disposici\u00f3n de la entidad la infraestructura necesaria para poder desarrollar su actividad (despacho, equipo inform\u00e1tico y otros servicios) y realizar\u00e1 una aportaci\u00f3n econ\u00f3mica de <strong>18.095 euros anuales.<\/strong><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Ayuntamiento de Cambrils y la Fundaci\u00f3n Privada Amigos de los Mayores han firmado un nuevo convenio para continuar trabajando a favor de las personas mayores en situaci\u00f3n de soledad. La actividad que desarrolla Amigos <a href=\"https:\/\/firagran.com\/es\/cambrils-renueva-el-convenio-para-luchar-contra-la-soledad-de-las-personas-mayores\/\"> [&#8230;]<\/a><\/p>\n","protected":false},"author":1,"featured_media":4823,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[28],"tags":[],"class_list":["post-4825","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-general-es"],"_links":{"self":[{"href":"https:\/\/firagran.com\/es\/wp-json\/wp\/v2\/posts\/4825","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/firagran.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/firagran.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/firagran.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/firagran.com\/es\/wp-json\/wp\/v2\/comments?post=4825"}],"version-history":[{"count":1,"href":"https:\/\/firagran.com\/es\/wp-json\/wp\/v2\/posts\/4825\/revisions"}],"predecessor-version":[{"id":4826,"href":"https:\/\/firagran.com\/es\/wp-json\/wp\/v2\/posts\/4825\/revisions\/4826"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/firagran.com\/es\/wp-json\/wp\/v2\/media\/4823"}],"wp:attachment":[{"href":"https:\/\/firagran.com\/es\/wp-json\/wp\/v2\/media?parent=4825"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/firagran.com\/es\/wp-json\/wp\/v2\/categories?post=4825"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/firagran.com\/es\/wp-json\/wp\/v2\/tags?post=4825"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}