{"id":5492,"date":"2018-06-14T08:55:00","date_gmt":"2018-06-14T06:55:00","guid":{"rendered":"https:\/\/firagran.com\/?p=5492"},"modified":"2018-06-12T16:55:48","modified_gmt":"2018-06-12T14:55:48","slug":"tarrega-imparte-talleres-de-memoria-para-potenciar-las-funciones-cognitivas-de-las-personas-mayores","status":"publish","type":"post","link":"https:\/\/firagran.com\/es\/tarrega-imparte-talleres-de-memoria-para-potenciar-las-funciones-cognitivas-de-las-personas-mayores\/","title":{"rendered":"T\u00e0rrega imparte talleres de memoria para potenciar las funciones cognitivas de las personas mayores"},"content":{"rendered":"<p>La Concejal\u00eda de Promoci\u00f3n de la Salud de T\u00e0rrega ha impartido la segunda edici\u00f3n de sus talleres de memoria llamados &#8220;Gente Activa, Mente en Forma&#8221;. Dinamizado por profesionales de NeuroLleida con el apoyo de la Diputaci\u00f3n de Lleida, consiste en un programa de entrenamiento cognitivo en grupo y dirigido especialmente a personas mayores. Los participantes mejoran sus funciones cognitivas y desarrollan estrategias de salud cerebral para prevenir su empeoramiento con el paso del tiempo. Los talleres se han realizado desde el pasado octubre con 27 sesiones y un total de 23 personas participantes, con una media de edad de 70-75 a\u00f1os de edad.<\/p>\n<p>El programa tambi\u00e9n fomenta el empoderamiento de las personas mayores participantes. As\u00ed, en el marco de los talleres se abordan estas cuestiones: \u00bfC\u00f3mo funciona mi memoria? \u00bfC\u00f3mo puedo mejorar mi capacidad para prestar atenci\u00f3n a las cosas? \u00bfC\u00f3mo puedo mejorar el recuerdo (la consolidaci\u00f3n) de la informaci\u00f3n? \u00bfC\u00f3mo puedo mejorar la recuperaci\u00f3n de la informaci\u00f3n que tengo a mi memoria? \u00bfC\u00f3mo puedo mejorar mi memoria prospectiva? C\u00f3mo afecta el estado de \u00e1nimo en la memoria?<\/p>\n<p><strong>Fuente:<\/strong> tarrega.cat<\/p>\n<p><strong>Leer m\u00e1s:<\/strong> https:\/\/translate.google.es\/translate?hl=es&amp;sl=ca&amp;u=http:\/\/www.tarrega.cat\/esports-salut-gentgran\/noticies\/tallers-memoria&amp;prev=search<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Concejal\u00eda de Promoci\u00f3n de la Salud de T\u00e0rrega ha impartido la segunda edici\u00f3n de sus talleres de memoria llamados &#8220;Gente Activa, Mente en Forma&#8221;. Dinamizado por profesionales de NeuroLleida con el apoyo de la <a href=\"https:\/\/firagran.com\/es\/tarrega-imparte-talleres-de-memoria-para-potenciar-las-funciones-cognitivas-de-las-personas-mayores\/\"> [&#8230;]<\/a><\/p>\n","protected":false},"author":1,"featured_media":5483,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[75],"tags":[],"class_list":["post-5492","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-envejecimiento-activo"],"_links":{"self":[{"href":"https:\/\/firagran.com\/es\/wp-json\/wp\/v2\/posts\/5492","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/firagran.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/firagran.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/firagran.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/firagran.com\/es\/wp-json\/wp\/v2\/comments?post=5492"}],"version-history":[{"count":1,"href":"https:\/\/firagran.com\/es\/wp-json\/wp\/v2\/posts\/5492\/revisions"}],"predecessor-version":[{"id":5493,"href":"https:\/\/firagran.com\/es\/wp-json\/wp\/v2\/posts\/5492\/revisions\/5493"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/firagran.com\/es\/wp-json\/wp\/v2\/media\/5483"}],"wp:attachment":[{"href":"https:\/\/firagran.com\/es\/wp-json\/wp\/v2\/media?parent=5492"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/firagran.com\/es\/wp-json\/wp\/v2\/categories?post=5492"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/firagran.com\/es\/wp-json\/wp\/v2\/tags?post=5492"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}