{"id":5654,"date":"2018-06-28T08:36:09","date_gmt":"2018-06-28T06:36:09","guid":{"rendered":"https:\/\/firagran.com\/?p=5654"},"modified":"2018-06-25T10:37:07","modified_gmt":"2018-06-25T08:37:07","slug":"busqueda-de-voluntariado-para-ocio-y-formacion-para-personas-mayores","status":"publish","type":"post","link":"https:\/\/firagran.com\/es\/busqueda-de-voluntariado-para-ocio-y-formacion-para-personas-mayores\/","title":{"rendered":"B\u00fasqueda de \u201cVoluntariado\u201d para ocio y formaci\u00f3n para personas mayores"},"content":{"rendered":"<p>El Hogar de Ancianos Nuestra Casa es un espacio municipal para personas mayores en el barrio de Porta, en Nou Barris, Barcelona. En el Casal de Casa Nostra trabajamos para fomentar los roles activos de las personas mayores, ofreciendo espacios de participaci\u00f3n y relaci\u00f3n, y dando respuesta a las inquietudes y necesidades de las personas mayores del barrio. Actualmente hay en marcha diferentes actividades y talleres que permiten ofrecer un abanico de posibilidades donde todos tienen cabida. Queremos trabajar para seguir siendo un espacio de intercambio de experiencias y relaci\u00f3n, y por eso necesitamos gente motivada con ganas de dinamizar talleres en el casal, ofreciendo espacios de ocio y formaci\u00f3n.<\/p>\n<p>Buscamos personas voluntarias y \/ o estudiantes en pr\u00e1cticas que tengan ganas de compartir unas horas a la semana con gente mayor. No se requiere formaci\u00f3n espec\u00edfica, pero es interesante tener unos conocimientos m\u00ednimos de los talleres que se dinamizar\u00e1n. Si tienes una actitud positiva, motivaci\u00f3n y con ganas de compartir tu tiempo con personas mayores activas, en el Casal de Casa Nostra encontrar\u00e1s tu espacio! Actualmente buscamos voluntarios para dinamizar talleres de cocina (1 vez al mes) y Mandalas (1 vez por semana) pero estamos abiertas para cualquier propuesta!<\/p>\n<p><strong>Fuente:<\/strong> hacesfalta.org<\/p>\n<p><strong>Leer m\u00e1s:<\/strong> https:\/\/translate.google.es\/translate?hl=es&amp;sl=ca&amp;u=https:\/\/www.hacesfalta.org\/oportunidades\/voluntariado\/presencial\/detalle\/voluntariado-para-ocio-y-formacion-con-gente-mayor\/148975%3FpageIndex%3D1%26volver%3D%26idProvincia%3D5&amp;prev=search<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Hogar de Ancianos Nuestra Casa es un espacio municipal para personas mayores en el barrio de Porta, en Nou Barris, Barcelona. En el Casal de Casa Nostra trabajamos para fomentar los roles activos de <a href=\"https:\/\/firagran.com\/es\/busqueda-de-voluntariado-para-ocio-y-formacion-para-personas-mayores\/\"> [&#8230;]<\/a><\/p>\n","protected":false},"author":1,"featured_media":5643,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[75],"tags":[],"class_list":["post-5654","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-envejecimiento-activo"],"_links":{"self":[{"href":"https:\/\/firagran.com\/es\/wp-json\/wp\/v2\/posts\/5654","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/firagran.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/firagran.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/firagran.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/firagran.com\/es\/wp-json\/wp\/v2\/comments?post=5654"}],"version-history":[{"count":1,"href":"https:\/\/firagran.com\/es\/wp-json\/wp\/v2\/posts\/5654\/revisions"}],"predecessor-version":[{"id":5655,"href":"https:\/\/firagran.com\/es\/wp-json\/wp\/v2\/posts\/5654\/revisions\/5655"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/firagran.com\/es\/wp-json\/wp\/v2\/media\/5643"}],"wp:attachment":[{"href":"https:\/\/firagran.com\/es\/wp-json\/wp\/v2\/media?parent=5654"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/firagran.com\/es\/wp-json\/wp\/v2\/categories?post=5654"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/firagran.com\/es\/wp-json\/wp\/v2\/tags?post=5654"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}