{"id":6266,"date":"2018-08-14T09:00:18","date_gmt":"2018-08-14T07:00:18","guid":{"rendered":"https:\/\/firagran.com\/?p=6266"},"modified":"2018-07-26T10:29:56","modified_gmt":"2018-07-26T08:29:56","slug":"nou-barris-presenta-el-derecho-al-envejecimiento-y-al-envejecimiento-activo-en-el-distrito","status":"publish","type":"post","link":"https:\/\/firagran.com\/es\/nou-barris-presenta-el-derecho-al-envejecimiento-y-al-envejecimiento-activo-en-el-distrito\/","title":{"rendered":"Nou Barris presenta el \u201cDerecho al envejecimiento y al envejecimiento activo\u201d en el distrito"},"content":{"rendered":"<p>Nou Barris quiere ser un distrito que se preocupa y ocupa del proceso de envejecer, que quiere incidir en el ejercicio de derechos de este colectivo y reconocer el derecho a cuidar, a ser cuidado, a vivir en condiciones dignas y a garantizar el derecho a la ciudad a lo largo de la vida. Y tambi\u00e9n un distrito que quiere promover el envejecimiento activo de las personas que viven all\u00ed y tejer comunidad con ellas.<\/p>\n<p>De las 39.255 personas de 65 a\u00f1os y m\u00e1s que hay en Nou Barris, 9.966 viven solas. Eso representa el 25,4% del total, o lo que es lo mismo, una de cada cuatro.<\/p>\n<p>Bajo estas premisas, el Distrito ha preparado el \u201cDerecho al envejecimiento y al envejecimiento activo\u201d en Nou Barris, una medida de gobierno que se present\u00f3 en el transcurso del \u00faltimo Consejo Plenario, celebrado el 4 de julio.<\/p>\n<p>El equipo de gobierno hizo un resumen, incidiendo en los ejes principales: derecho a envejecer dignamente, promoci\u00f3n del envejecimiento activo, y convivencia y comunidad.<\/p>\n<p>Derecho a envejecer dignamente: Se centra en la prevenci\u00f3n, llegando a aquellas personas m\u00e1s vulnerables y activando los recursos adecuados en cada caso.<\/p>\n<p>Promoci\u00f3n del envejecimiento activo: Se hace referencia a aquella serie de acciones y actividades encaminadas a fomentar el envejecimiento activo y la participaci\u00f3n y que act\u00faan de forma preventiva para evitar el deterioro de la salud y el aislamiento social.<\/p>\n<p>Convivencia y comunidad: La acci\u00f3n comunitaria es imprescindible para hacer un distrito inclusivo, adem\u00e1s de crear marcos de corresponsabilidad entre los diferentes servicios y la poblaci\u00f3n de los barrios, y luchar contra el aislamiento. Abre un abanico para trabajar la convivencia intergeneracional, haciendo de Nou Barris un distrito amable con las personas mayores.<\/p>\n<p><strong>Fuente:<\/strong> eixmaragall.com<\/p>\n<p><strong>Leer m\u00e1s:<\/strong> https:\/\/www.eixmaragall.com\/es\/noticia\/nou-barris-presenta-el-derecho-al-envejecimiento-y-al-envejecimiento-activo-en-el-distrito<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nou Barris quiere ser un distrito que se preocupa y ocupa del proceso de envejecer, que quiere incidir en el ejercicio de derechos de este colectivo y reconocer el derecho a cuidar, a ser cuidado, <a href=\"https:\/\/firagran.com\/es\/nou-barris-presenta-el-derecho-al-envejecimiento-y-al-envejecimiento-activo-en-el-distrito\/\"> [&#8230;]<\/a><\/p>\n","protected":false},"author":1,"featured_media":6267,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[75],"tags":[],"class_list":["post-6266","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-envejecimiento-activo"],"_links":{"self":[{"href":"https:\/\/firagran.com\/es\/wp-json\/wp\/v2\/posts\/6266","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/firagran.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/firagran.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/firagran.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/firagran.com\/es\/wp-json\/wp\/v2\/comments?post=6266"}],"version-history":[{"count":1,"href":"https:\/\/firagran.com\/es\/wp-json\/wp\/v2\/posts\/6266\/revisions"}],"predecessor-version":[{"id":6269,"href":"https:\/\/firagran.com\/es\/wp-json\/wp\/v2\/posts\/6266\/revisions\/6269"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/firagran.com\/es\/wp-json\/wp\/v2\/media\/6267"}],"wp:attachment":[{"href":"https:\/\/firagran.com\/es\/wp-json\/wp\/v2\/media?parent=6266"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/firagran.com\/es\/wp-json\/wp\/v2\/categories?post=6266"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/firagran.com\/es\/wp-json\/wp\/v2\/tags?post=6266"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}