{"id":6357,"date":"2018-08-27T09:00:31","date_gmt":"2018-08-27T07:00:31","guid":{"rendered":"https:\/\/firagran.com\/?p=6357"},"modified":"2018-08-24T14:17:40","modified_gmt":"2018-08-24T12:17:40","slug":"entrevista-a-gemma-bruna-las-administraciones-tienen-poca-sensibilidad-ante-la-situacion-de-ayuda","status":"publish","type":"post","link":"https:\/\/firagran.com\/es\/entrevista-a-gemma-bruna-las-administraciones-tienen-poca-sensibilidad-ante-la-situacion-de-ayuda\/","title":{"rendered":"Entrevista a Gemma Bruna: &#8220;Las administraciones tienen poca sensibilidad ante la situaci\u00f3n de ayuda&#8221;"},"content":{"rendered":"<p>Entrevistadora: Ana Basanta<\/p>\n<p>La periodista Gemma Bruna ha escrito, junto con el enfermero Jos\u00e9 Par\u00eds, &#8216;Cu\u00eddate. Quince vivencias personales de cuidadores &#8216;(Plataforma), un libro sobre la importancia de estos acompa\u00f1antes menudo invisibles, de los que destaca el proceso de aprendizaje interno al estar en contacto continuo con el sufrimiento.<\/p>\n<p>Tenemos claro que para cuidar bien a los dem\u00e1s, primero debemos estar bien nosotros?<\/p>\n<p>Yo creo que no. Hay testimonios en el libro que al final se acaban vertiendo tanto a la hora de cuidar que se cuidan poco ellos mismos. Por ejemplo, una hija que cuida a su madre enferma de Alzheimer, que est\u00e1 ingresada, y realmente lo que transmite es que se cuida poco a s\u00ed misma y prioriza poco su entorno. En este caso, su marido y su hijo. Est\u00e1 tan abocada a la p\u00e9rdida de memoria de su madre, que se prioriza poco a ella misma.<\/p>\n<p>Luego hay otros testigos que podr\u00edan ejemplificar esta situaci\u00f3n de cuidarse poco a ellos mismos, pero yo creo que s\u00ed, que es complicado, al menos en los casos que hemos entrevistado. Tambi\u00e9n pienso que depende de la fase en la que est\u00e9s. Hay cuidadores que llevan muchos a\u00f1os cuidando la persona.<\/p>\n<div class=\"video-shortcode\">\n<div id=\"fb-root\"><\/div>\n<p><script>(function(d, s, id) {  var js, fjs = d.getElementsByTagName(s)[0];  if (d.getElementById(id)) return;  js = d.createElement(s); js.id = id;  js.src = 'https:\/\/connect.facebook.net\/es_ES\/sdk.js#xfbml=1&version=v3.1';  fjs.parentNode.insertBefore(js, fjs);}(document, 'script', 'facebook-jssdk'));<\/script><\/p>\n<div class=\"fb-video\" data-href=\"https:\/\/www.facebook.com\/catalunyapress\/videos\/1975326835845198\/\" data-width=\"1200\">\n<blockquote cite=\"https:\/\/www.facebook.com\/catalunyapress\/videos\/1975326835845198\/\" class=\"fb-xfbml-parse-ignore\"><p><a href=\"https:\/\/www.facebook.com\/catalunyapress\/videos\/1975326835845198\/\">Entrevista Gemma Bruna<\/a><\/p>\n<p>Coautora del llibre &#039;Cu\u00eddate. Quince vivencias personales de cuidadores&#039;. https:\/\/www.catalunyapress.cat\/texto-diario\/mostrar\/1153350\/gemma-bruna-administracions-tenen-poca-sensibilitat-davant-situacio-dajut<\/p>\n<p>Publicada por <a href=\"https:\/\/www.facebook.com\/catalunyapress\/\">CatalunyaPress<\/a> en Viernes, 17 de agosto de 2018<\/p><\/blockquote>\n<\/div>\n<\/div>\n<p><strong>Fuente:<\/strong> catalunyapress.cat<\/p>\n<p><strong>Leer m\u00e1s:<\/strong> https:\/\/translate.google.es\/translate?hl=es&amp;sl=ca&amp;u=https:\/\/www.catalunyapress.cat\/texto-diario\/mostrar\/1153350\/gemma-bruna-administracions-tenen-poca-sensibilitat-davant-situacio-dajut&amp;prev=search<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Entrevistadora: Ana Basanta La periodista Gemma Bruna ha escrito, junto con el enfermero Jos\u00e9 Par\u00eds, &#8216;Cu\u00eddate. Quince vivencias personales de cuidadores &#8216;(Plataforma), un libro sobre la importancia de estos acompa\u00f1antes menudo invisibles, de los que <a href=\"https:\/\/firagran.com\/es\/entrevista-a-gemma-bruna-las-administraciones-tienen-poca-sensibilidad-ante-la-situacion-de-ayuda\/\"> [&#8230;]<\/a><\/p>\n","protected":false},"author":1,"featured_media":6351,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[74],"tags":[],"class_list":["post-6357","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entrevistas"],"_links":{"self":[{"href":"https:\/\/firagran.com\/es\/wp-json\/wp\/v2\/posts\/6357","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/firagran.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/firagran.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/firagran.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/firagran.com\/es\/wp-json\/wp\/v2\/comments?post=6357"}],"version-history":[{"count":1,"href":"https:\/\/firagran.com\/es\/wp-json\/wp\/v2\/posts\/6357\/revisions"}],"predecessor-version":[{"id":6358,"href":"https:\/\/firagran.com\/es\/wp-json\/wp\/v2\/posts\/6357\/revisions\/6358"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/firagran.com\/es\/wp-json\/wp\/v2\/media\/6351"}],"wp:attachment":[{"href":"https:\/\/firagran.com\/es\/wp-json\/wp\/v2\/media?parent=6357"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/firagran.com\/es\/wp-json\/wp\/v2\/categories?post=6357"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/firagran.com\/es\/wp-json\/wp\/v2\/tags?post=6357"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}