{"id":6922,"date":"2018-12-04T09:00:08","date_gmt":"2018-12-04T08:00:08","guid":{"rendered":"https:\/\/firagran.com\/?p=6922"},"modified":"2018-11-29T12:24:36","modified_gmt":"2018-11-29T11:24:36","slug":"las-personas-mayores-de-mollet-vuelve-a-celebrar-el-encuentro-poetico-poetas-mayores","status":"publish","type":"post","link":"https:\/\/firagran.com\/es\/las-personas-mayores-de-mollet-vuelve-a-celebrar-el-encuentro-poetico-poetas-mayores\/","title":{"rendered":"Las personas mayores de Mollet vuelve a celebrar el encuentro po\u00e9tico Poetas Mayores"},"content":{"rendered":"<p><span lang=\"CA\" style=\"margin: 0px; line-height: 115%; font-family: 'Arial','sans-serif'; font-size: 12pt;\"><span style=\"color: #000000;\">El Ayuntamiento de Mollet del Vall\u00e9s, a trav\u00e9s de la concejal\u00eda de Mayores, con la colaboraci\u00f3n de los centros y entidades de personas mayores de la ciudad, organiz\u00f3 este mi\u00e9rcoles 21 de noviembre, en el Centro de Servicios El Lledoner un a\u00f1o m\u00e1s , el encuentro po\u00e9tico Poetas Grandes. <\/span><\/span><\/p>\n<p><span lang=\"CA\" style=\"margin: 0px; line-height: 115%; font-family: 'Arial','sans-serif'; font-size: 12pt;\"><span style=\"color: #000000;\">Esta fue la 23\u00aa edici\u00f3n de Poetas Grandes, una iniciativa que naci\u00f3 en 1995 para ofrecer una plataforma a los poetas y poetisas grandes de la ciudad en la que pudieran expresar sus inquietudes po\u00e9ticas y creativas. <\/span><\/span><\/p>\n<p><span lang=\"CA\" style=\"margin: 0px; line-height: 115%; font-family: 'Arial','sans-serif'; font-size: 12pt;\"><span style=\"color: #000000;\">Este a\u00f1o, han participado 25 poetas y poetisas, 12 mujeres y 13 hombres, que han presentado un total de 47 poes\u00edas con tem\u00e1ticas tan variadas como el amor, la familia, la naturaleza, la tierra de procedencia, etc. <\/span><\/span><\/p>\n<p><span lang=\"CA\" style=\"margin: 0px; line-height: 115%; font-family: 'Arial','sans-serif'; font-size: 12pt;\"><span style=\"color: #000000;\">El acto, que estuvo amenizado por la compa\u00f1\u00eda Un cuento en el saco, cont\u00f3 con la presencia de la concejala de Mayores Ana M\u00aa D\u00edaz<\/span><\/span>.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Fuente: <\/strong><span style=\"margin: 0px; line-height: 115%; font-family: 'Arial','sans-serif'; font-size: 12pt;\"><span style=\"color: #000000;\">clicama.cat<\/span><\/span><\/p>\n<p><strong>Leer m\u00e1s: <\/strong><a href=\"https:\/\/translate.google.es\/translate?hl=es&amp;sl=ca&amp;u=https:\/\/www.clicama.cat\/articulo\/cultura\/gent-gran-mollet-torna-celebrar-trobada-poetica-poetes-grans\/20181122115515032148.html&amp;prev=search\">https:\/\/translate.google.es\/translate?hl=es&amp;sl=ca&amp;u=https:\/\/www.clicama.cat\/articulo\/cultura\/gent-gran-mollet-torna-celebrar-trobada-poetica-poetes-grans\/20181122115515032148.html&amp;prev=search<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Ayuntamiento de Mollet del Vall\u00e9s, a trav\u00e9s de la concejal\u00eda de Mayores, con la colaboraci\u00f3n de los centros y entidades de personas mayores de la ciudad, organiz\u00f3 este mi\u00e9rcoles 21 de noviembre, en el <a href=\"https:\/\/firagran.com\/es\/las-personas-mayores-de-mollet-vuelve-a-celebrar-el-encuentro-poetico-poetas-mayores\/\"> [&#8230;]<\/a><\/p>\n","protected":false},"author":1,"featured_media":6911,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[75],"tags":[],"class_list":["post-6922","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-envejecimiento-activo"],"_links":{"self":[{"href":"https:\/\/firagran.com\/es\/wp-json\/wp\/v2\/posts\/6922","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/firagran.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/firagran.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/firagran.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/firagran.com\/es\/wp-json\/wp\/v2\/comments?post=6922"}],"version-history":[{"count":2,"href":"https:\/\/firagran.com\/es\/wp-json\/wp\/v2\/posts\/6922\/revisions"}],"predecessor-version":[{"id":6962,"href":"https:\/\/firagran.com\/es\/wp-json\/wp\/v2\/posts\/6922\/revisions\/6962"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/firagran.com\/es\/wp-json\/wp\/v2\/media\/6911"}],"wp:attachment":[{"href":"https:\/\/firagran.com\/es\/wp-json\/wp\/v2\/media?parent=6922"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/firagran.com\/es\/wp-json\/wp\/v2\/categories?post=6922"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/firagran.com\/es\/wp-json\/wp\/v2\/tags?post=6922"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}