{"id":6973,"date":"2018-12-07T11:30:20","date_gmt":"2018-12-07T10:30:20","guid":{"rendered":"https:\/\/firagran.com\/?p=6973"},"modified":"2018-12-04T12:45:02","modified_gmt":"2018-12-04T11:45:02","slug":"amigos-de-los-mayores-recibe-el-galardon-tatiana-sisquella","status":"publish","type":"post","link":"https:\/\/firagran.com\/es\/amigos-de-los-mayores-recibe-el-galardon-tatiana-sisquella\/","title":{"rendered":"Amigos de los Mayores recibe el galard\u00f3n Tatiana Sisquella"},"content":{"rendered":"<div class=\"video-shortcode\"><iframe width=\"1200\" height=\"675\" src=\"https:\/\/www.youtube.com\/embed\/pFq_3yXUTDs?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div>\n<p>&nbsp;<\/p>\n<p>La entidad trabaja para combatir el aislamiento en que viven muchas personas de la tercera edad<\/p>\n<p>La fundaci\u00f3n Amigos de los Mayores ha sido distinguida con el quinto premio Tatiana Sisquella a la contribuci\u00f3n social, que se ha entregado este jueves por la tarde, en el marco de la Noche de la ARA. Desde su creaci\u00f3n, en 1987, esta entidad se dedica a &#8220;dinamizar la solidaridad colectiva de la sociedad apoyando a las personas mayores que viven solas&#8221;, en palabras de su presidente, Francisco Patricio. Actualmente la fundaci\u00f3n cuenta con unos 1.800 voluntarios que atienden aproximadamente 1.800 personas, a las que hacen, al menos, una visita cada semana. &#8220;Todos nos haremos grandes, pero no estamos educados para el envejecimiento: no saben hacer frente a la p\u00e9rdida de los seres queridos. El mismo envejecimiento y el ritmo de vida llevan a un cierto aislamiento, y m\u00e1s si no tienes herramientas personales para no sentirte solo y vivir en colectividad &#8220;, reflexiona Patricio. &#8220;Sigue habiendo mucha gente mayor que se siente sola -a\u00f1ade-. Por ello es necesario que existan entidades como la nuestra y, sobre todo, voluntarios como los que tenemos\u201d.<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>Fuente: <\/strong>ara.cat<\/p>\n<p><strong>Leer m\u00e1s: <\/strong><a href=\"https:\/\/translate.google.es\/translate?hl=es&amp;sl=ca&amp;u=https:\/\/www.ara.cat\/media\/Amics-Gent-Gran-Tatiana-Sisquella_0_2133986778.html&amp;prev=search\">https:\/\/translate.google.es\/translate?hl=es&amp;sl=ca&amp;u=https:\/\/www.ara.cat\/media\/Amics-Gent-Gran-Tatiana-Sisquella_0_2133986778.html&amp;prev=search<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; La entidad trabaja para combatir el aislamiento en que viven muchas personas de la tercera edad La fundaci\u00f3n Amigos de los Mayores ha sido distinguida con el quinto premio Tatiana Sisquella a la contribuci\u00f3n <a href=\"https:\/\/firagran.com\/es\/amigos-de-los-mayores-recibe-el-galardon-tatiana-sisquella\/\"> [&#8230;]<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[75],"tags":[],"class_list":["post-6973","post","type-post","status-publish","format-standard","hentry","category-envejecimiento-activo"],"_links":{"self":[{"href":"https:\/\/firagran.com\/es\/wp-json\/wp\/v2\/posts\/6973","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/firagran.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/firagran.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/firagran.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/firagran.com\/es\/wp-json\/wp\/v2\/comments?post=6973"}],"version-history":[{"count":1,"href":"https:\/\/firagran.com\/es\/wp-json\/wp\/v2\/posts\/6973\/revisions"}],"predecessor-version":[{"id":6974,"href":"https:\/\/firagran.com\/es\/wp-json\/wp\/v2\/posts\/6973\/revisions\/6974"}],"wp:attachment":[{"href":"https:\/\/firagran.com\/es\/wp-json\/wp\/v2\/media?parent=6973"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/firagran.com\/es\/wp-json\/wp\/v2\/categories?post=6973"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/firagran.com\/es\/wp-json\/wp\/v2\/tags?post=6973"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}