{"id":7185,"date":"2019-01-14T09:00:07","date_gmt":"2019-01-14T08:00:07","guid":{"rendered":"https:\/\/firagran.com\/?p=7185"},"modified":"2019-01-16T12:20:24","modified_gmt":"2019-01-16T11:20:24","slug":"se-constituye-formalmente-el-senado-de-la-tercera-edad-de-constantino","status":"publish","type":"post","link":"https:\/\/firagran.com\/es\/se-constituye-formalmente-el-senado-de-la-tercera-edad-de-constantino\/","title":{"rendered":"Se constituye formalmente el Senado de la tercera edad de Constantino"},"content":{"rendered":"<p>La Sala de Plenos del Ayuntamiento de Constant\u00ed acogi\u00f3 el viernes, 21 de diciembre, el acto de constituci\u00f3n formal del Senado de la Gent Gran. El acto ha sido presidido por el alcalde de Constant\u00ed, Oscar S\u00e1nchez, y ha contado con la presencia de los seis senadores que conformar\u00e1n el cargo.<\/p>\n<p>Los senadores se han comprometido formalmente a desarrollar las acciones correspondientes a este \u00f3rgano, que tiene por objetivo ofrecer un espacio de di\u00e1logo y reflexi\u00f3n sobre el Constantino actual y de futuro. Tambi\u00e9n se ha fijado el mes de marzo del a\u00f1o pr\u00f3ximo como la fecha para realizar la primera de las sesiones del Senado.<\/p>\n<p><strong>Fuente: <\/strong>diarimes.com<\/p>\n<p><strong>Leer m\u00e1s: <\/strong><a href=\"https:\/\/translate.google.es\/translate?hl=es&amp;sl=ca&amp;u=https:\/\/www.diarimes.com\/noticies\/vida_social\/2018\/12\/21\/es_constitueix_formalment_senat_gent_gran_constanti_51817_3047.html&amp;prev=search\">https:\/\/translate.google.es\/translate?hl=es&amp;sl=ca&amp;u=https:\/\/www.diarimes.com\/noticies\/vida_social\/2018\/12\/21\/es_constitueix_formalment_senat_gent_gran_constanti_51817_3047.html&amp;prev=search<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Sala de Plenos del Ayuntamiento de Constant\u00ed acogi\u00f3 el viernes, 21 de diciembre, el acto de constituci\u00f3n formal del Senado de la Gent Gran. El acto ha sido presidido por el alcalde de Constant\u00ed, <a href=\"https:\/\/firagran.com\/es\/se-constituye-formalmente-el-senado-de-la-tercera-edad-de-constantino\/\"> [&#8230;]<\/a><\/p>\n","protected":false},"author":1,"featured_media":7186,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[75],"tags":[],"class_list":["post-7185","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-envejecimiento-activo"],"_links":{"self":[{"href":"https:\/\/firagran.com\/es\/wp-json\/wp\/v2\/posts\/7185","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/firagran.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/firagran.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/firagran.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/firagran.com\/es\/wp-json\/wp\/v2\/comments?post=7185"}],"version-history":[{"count":3,"href":"https:\/\/firagran.com\/es\/wp-json\/wp\/v2\/posts\/7185\/revisions"}],"predecessor-version":[{"id":7275,"href":"https:\/\/firagran.com\/es\/wp-json\/wp\/v2\/posts\/7185\/revisions\/7275"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/firagran.com\/es\/wp-json\/wp\/v2\/media\/7186"}],"wp:attachment":[{"href":"https:\/\/firagran.com\/es\/wp-json\/wp\/v2\/media?parent=7185"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/firagran.com\/es\/wp-json\/wp\/v2\/categories?post=7185"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/firagran.com\/es\/wp-json\/wp\/v2\/tags?post=7185"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}