{"id":7617,"date":"2019-03-25T08:50:54","date_gmt":"2019-03-25T07:50:54","guid":{"rendered":"https:\/\/firagran.com\/?p=7617"},"modified":"2019-03-18T12:17:21","modified_gmt":"2019-03-18T11:17:21","slug":"la-residencia-la-tardor-ha-invitado-los-ciudadanos-a-sumarse-al-baile-de-mascaras-que-ha-celebrado-en-las-nuevas-instalaciones","status":"publish","type":"post","link":"https:\/\/firagran.com\/es\/la-residencia-la-tardor-ha-invitado-los-ciudadanos-a-sumarse-al-baile-de-mascaras-que-ha-celebrado-en-las-nuevas-instalaciones\/","title":{"rendered":"La residencia La Tardor ha invitado los ciudadanos a sumarse al baile de m\u00e1scaras que ha celebrado en las nuevas instalaciones"},"content":{"rendered":"<p>Esta semana tambi\u00e9n ha sido Carnaval en las residencias de gente mayor de la Garrotxa. La Tardor de Olot lo celebr\u00f3 el viernes, con una fiesta que siempre tiene marcada en el calendario pero que este a\u00f1o ha querido que sea m\u00e1s especial aprovechando las nuevas\u00a0instalaciones La residencia\u00a0olotina\u00a0abri\u00f3 puertas para invitar los ciudadanos a participar.<\/p>\n<p>Fuente: garrotxadigital.cat<\/p>\n<p>Leer m\u00e1s: <a href=\"https:\/\/www.garrotxadigital.cat\/2019\/03\/09\/la-residencia-la-tardor-ha-convicat-els-ciutadans-a-sumar-se-al-seu-ball-de-mascares-amb-motiu-del-carnaval\/\">https:\/\/www.garrotxadigital.cat\/2019\/03\/09\/la-residencia-la-tardor-ha-convicat-els-ciutadans-a-sumar-se-al-seu-ball-de-mascares-amb-motiu-del-carnaval\/<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Esta semana tambi\u00e9n ha sido Carnaval en las residencias de gente mayor de la Garrotxa. La Tardor de Olot lo celebr\u00f3 el viernes, con una fiesta que siempre tiene marcada en el calendario pero que <a href=\"https:\/\/firagran.com\/es\/la-residencia-la-tardor-ha-invitado-los-ciudadanos-a-sumarse-al-baile-de-mascaras-que-ha-celebrado-en-las-nuevas-instalaciones\/\"> [&#8230;]<\/a><\/p>\n","protected":false},"author":2,"featured_media":7595,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[75],"tags":[],"class_list":["post-7617","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-envejecimiento-activo"],"_links":{"self":[{"href":"https:\/\/firagran.com\/es\/wp-json\/wp\/v2\/posts\/7617","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/firagran.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/firagran.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/firagran.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/firagran.com\/es\/wp-json\/wp\/v2\/comments?post=7617"}],"version-history":[{"count":1,"href":"https:\/\/firagran.com\/es\/wp-json\/wp\/v2\/posts\/7617\/revisions"}],"predecessor-version":[{"id":7618,"href":"https:\/\/firagran.com\/es\/wp-json\/wp\/v2\/posts\/7617\/revisions\/7618"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/firagran.com\/es\/wp-json\/wp\/v2\/media\/7595"}],"wp:attachment":[{"href":"https:\/\/firagran.com\/es\/wp-json\/wp\/v2\/media?parent=7617"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/firagran.com\/es\/wp-json\/wp\/v2\/categories?post=7617"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/firagran.com\/es\/wp-json\/wp\/v2\/tags?post=7617"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}