{"id":8276,"date":"2019-06-06T09:00:36","date_gmt":"2019-06-06T07:00:36","guid":{"rendered":"https:\/\/firagran.com\/?p=8276"},"modified":"2019-06-05T10:45:28","modified_gmt":"2019-06-05T08:45:28","slug":"presentacion-de-la-encuesta-a-firagran-2019-la-soledad-de-las-personas-mayores","status":"publish","type":"post","link":"https:\/\/firagran.com\/es\/presentacion-de-la-encuesta-a-firagran-2019-la-soledad-de-las-personas-mayores\/","title":{"rendered":"Presentaci\u00f3n de la encuesta a FiraGran 2019: La soledad de las personas mayores"},"content":{"rendered":"<p><span style=\"margin: 0px; line-height: 107%; font-family: 'Times New Roman',serif; font-size: 12pt;\"><span style=\"color: #000000;\">Dentro del marco de la 21ena Edici\u00f3n de la FiraGran 2019 organizada del 12 al 15 de junio, os invitamos a la presentaci\u00f3n de la encuesta sobre la soledad de las personas mayores. Esta encuesta ha sido elaborada por la Fundaci\u00f3n Memora con la colaboraci\u00f3n de la Fundaci\u00f3n FiraGran y la Asociaci\u00f3n Siena. <\/span><\/span><\/p>\n<p><span style=\"margin: 0px; line-height: 107%; font-family: 'Times New Roman',serif; font-size: 12pt;\"><span style=\"color: #000000;\">El acto ser\u00e1 el primer d\u00eda de la feria el 12 de junio, al Auditorio de les Drassanes Reials de Barcelona a les 10h.<\/span><\/span><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"margin: 0px; line-height: 107%; font-family: 'Times New Roman',serif; font-size: 12pt;\"><span style=\"color: #000000;\">\u00a0<\/span><\/span><\/p>\n<p><span style=\"margin: 0px; line-height: 107%; font-family: 'Times New Roman',serif; font-size: 12pt;\"><span style=\"color: #000000;\">\u00a0<\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dentro del marco de la 21ena Edici\u00f3n de la FiraGran 2019 organizada del 12 al 15 de junio, os invitamos a la presentaci\u00f3n de la encuesta sobre la soledad de las personas mayores. Esta encuesta <a href=\"https:\/\/firagran.com\/es\/presentacion-de-la-encuesta-a-firagran-2019-la-soledad-de-las-personas-mayores\/\"> [&#8230;]<\/a><\/p>\n","protected":false},"author":2,"featured_media":8277,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[28],"tags":[],"class_list":["post-8276","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-general-es"],"_links":{"self":[{"href":"https:\/\/firagran.com\/es\/wp-json\/wp\/v2\/posts\/8276","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/firagran.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/firagran.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/firagran.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/firagran.com\/es\/wp-json\/wp\/v2\/comments?post=8276"}],"version-history":[{"count":1,"href":"https:\/\/firagran.com\/es\/wp-json\/wp\/v2\/posts\/8276\/revisions"}],"predecessor-version":[{"id":8279,"href":"https:\/\/firagran.com\/es\/wp-json\/wp\/v2\/posts\/8276\/revisions\/8279"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/firagran.com\/es\/wp-json\/wp\/v2\/media\/8277"}],"wp:attachment":[{"href":"https:\/\/firagran.com\/es\/wp-json\/wp\/v2\/media?parent=8276"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/firagran.com\/es\/wp-json\/wp\/v2\/categories?post=8276"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/firagran.com\/es\/wp-json\/wp\/v2\/tags?post=8276"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}