{"id":8935,"date":"2019-08-05T09:00:12","date_gmt":"2019-08-05T07:00:12","guid":{"rendered":"https:\/\/firagran.com\/?p=8935"},"modified":"2019-07-24T13:51:26","modified_gmt":"2019-07-24T11:51:26","slug":"los-mayores-se-sienten-mas-solos-ahora-en-verano-que-en-navidad","status":"publish","type":"post","link":"https:\/\/firagran.com\/es\/los-mayores-se-sienten-mas-solos-ahora-en-verano-que-en-navidad\/","title":{"rendered":"Los mayores se sienten m\u00e1s solos ahora en verano que en Navidad"},"content":{"rendered":"<p><b><span style=\"margin: 0px; color: black; line-height: 107%; font-family: 'Times New Roman',serif; font-size: 12pt;\">El 11,4% de las personas mayores afirman sentirse solas a diario, un sentimiento que crece en la \u00e9poca estival<\/span><\/b><\/p>\n<p>Esta \u00e9poca del a\u00f1o es la que m\u00e1s cuesta arriba se hace a las generaciones m\u00e1s mayores<span style=\"margin: 0px; color: black; line-height: 107%; letter-spacing: 0.25pt; font-family: 'Times New Roman',serif; font-size: 12pt;\"> de nuestra sociedad debido a las altas temperaturas y el sentimiento de soledad que se incrementa en verano. Espa\u00f1a es una de las poblaciones con los niveles de envejecimiento m\u00e1s altos y, de hecho, seg\u00fan el Instituto Nacional de Estad\u00edstica (INE), se contabilizan 120 mayores de 64 a\u00f1os por cada 100 menos de 16; estamos ante una seria problem\u00e1tica sobre c\u00f3mo cuidar a los m\u00e1s mayores en verano.\u00a0 El verano suele ser una \u00e9poca del a\u00f1o muy complicada para la gente mayor y, especialmente, para la que se siente sola. De acuerdo con las \u00faltimas cifras del <\/span><span style=\"font-family: Calibri;\"><span style=\"color: #000000;\">IMSERSO (Instituto de Mayores y Servicios Sociales), el 11,4% de las personas mayores afirmaron sentirse solas a diario. Estas cifras pueden verse incrementadas con la llegada del verano, cuando los mayores se quedan sin compa\u00f1\u00eda como resultado de los viajes de vacaciones de familiares, amigos y vecinos.<\/span><\/span><\/p>\n<p><span style=\"margin: 0px; color: black; line-height: 107%; letter-spacing: 0.25pt; font-family: 'Times New Roman',serif; font-size: 12pt;\">Fuente: ABC<\/span><\/p>\n<p><span style=\"margin: 0px; color: black; line-height: 107%; letter-spacing: 0.25pt; font-family: 'Times New Roman',serif; font-size: 12pt;\">Leer m\u00e1s:<\/span> <span style=\"margin: 0px; color: black; line-height: 107%; letter-spacing: 0.25pt; font-family: 'Times New Roman',serif; font-size: 12pt;\"><a href=\"https:\/\/www.abc.es\/familia\/mayores\/abci-mayores-sienten-mas-solos-ahora-verano-navidad-201907210124_noticia.html\">https:\/\/www.abc.es\/familia\/mayores\/abci-mayores-sienten-mas-solos-ahora-verano-navidad-201907210124_noticia.html<\/a><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El 11,4% de las personas mayores afirman sentirse solas a diario, un sentimiento que crece en la \u00e9poca estival Esta \u00e9poca del a\u00f1o es la que m\u00e1s cuesta arriba se hace a las generaciones m\u00e1s <a href=\"https:\/\/firagran.com\/es\/los-mayores-se-sienten-mas-solos-ahora-en-verano-que-en-navidad\/\"> [&#8230;]<\/a><\/p>\n","protected":false},"author":2,"featured_media":8936,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[28],"tags":[],"class_list":["post-8935","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-general-es"],"_links":{"self":[{"href":"https:\/\/firagran.com\/es\/wp-json\/wp\/v2\/posts\/8935","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/firagran.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/firagran.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/firagran.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/firagran.com\/es\/wp-json\/wp\/v2\/comments?post=8935"}],"version-history":[{"count":1,"href":"https:\/\/firagran.com\/es\/wp-json\/wp\/v2\/posts\/8935\/revisions"}],"predecessor-version":[{"id":8938,"href":"https:\/\/firagran.com\/es\/wp-json\/wp\/v2\/posts\/8935\/revisions\/8938"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/firagran.com\/es\/wp-json\/wp\/v2\/media\/8936"}],"wp:attachment":[{"href":"https:\/\/firagran.com\/es\/wp-json\/wp\/v2\/media?parent=8935"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/firagran.com\/es\/wp-json\/wp\/v2\/categories?post=8935"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/firagran.com\/es\/wp-json\/wp\/v2\/tags?post=8935"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}